{"id":25,"count":1,"description":"","link":"https:\/\/www.djabydesign.com\/index.php\/category\/nov4\/","name":"nov4","slug":"nov4","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/www.djabydesign.com\/index.php\/wp-json\/wp\/v2\/categories\/25","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.djabydesign.com\/index.php\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/www.djabydesign.com\/index.php\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/www.djabydesign.com\/index.php\/wp-json\/wp\/v2\/posts?categories=25"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}